{"id":16511,"date":"2017-07-08T11:05:18","date_gmt":"2017-07-08T09:05:18","guid":{"rendered":"https:\/\/www.aquimicasa.net\/blog\/?p=16511"},"modified":"2020-04-02T18:47:28","modified_gmt":"2020-04-02T16:47:28","slug":"tc","status":"publish","type":"post","link":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/","title":{"rendered":"El Tribunal Supremo afea su conducta a los bancos"},"content":{"rendered":"<p>Intentando no devolver el dinero percibido de m\u00e1s por las cl\u00e1usulas abusivas, los bancos dificultan y demoran los juicios para que los usuarios desistan. Su estrategia de que los usuarios que reclamen paguen las costas judiciales se acaba de ver cortada por una sentencia del Tribunal Supremo. \u00a0As\u00ed, los bancos deber\u00e1n abonar las costas judiciales de las dos instancias previas al recurso de casaci\u00f3n en materia de cl\u00e1usulas suelo abusivas, seg\u00fan ha acordado en pleno el Tribunal Supremo, que ha adoptado dicha medida para evitar que los gastos del proceso tengan, como intentaban los bancos, \u00a0un<strong> efecto disuasorio en los consumidores afectados<\/strong>.<\/p>\n<p>En su sentencia, la sala de lo Civil del Alto Tribunal, presidida por el juez Francisco Mar\u00edn Cast\u00e1n, defiende la necesidad de esta orden pues si el cliente, a pesar de vencer el litigio, tuviera que abonar las costas judiciales, ello podr\u00eda suponer que otros afectados <strong>no acudieran a los tribunales por cantidades poco significativas<\/strong> y el \u00fanico beneficiado fuera el culpable, es decir, la banca. El fallo, que cuenta con el voto particular de tres magistrados, estima de este modo el recurso interpuesto por un usuario de CaixaBank contra la sentencia de la Audiencia Provincial de \u00c1lava, que declar\u00f3 la nulidad de la cl\u00e1usula aunque eximi\u00f3 a la entidad de dicho pago en junio de 2015. Sin embargo, la decisi\u00f3n del Tribunal de Justicia de la Uni\u00f3n Europea (TJUE), que el pasado diciembre concedi\u00f3 la plena retroactividad a todos quienes suscribieron un contrato hipotecario de tales caracter\u00edsticas, abr\u00eda una nueva v\u00eda a los perjudicados para que \u00e9stos solicitaran el reintegro de las cantidades que abonadas de m\u00e1s de forma indebida, teniendo que asumir, eso si, las costas judiciales.\u00a0 Se producir\u00eda un<strong> efecto disuasorio inverso\u00a0<\/strong>para que los consumidores no promovieran litigios por cantidades moderadas.<\/p>\n<p>As\u00ed lo reconoce la sala, que avala la petici\u00f3n del cliente ya que, en su opini\u00f3n, de ratificar el criterio anterior \u00abse producir\u00eda un efecto disuasorio inverso, no para que los bancos dejaran de incluir las cl\u00e1usulas suelo en los pr\u00e9stamos hipotecarios sino para que <strong>los consumidores no promovieran litigios por cantidades moderadas<\/strong>\u00ab. De igual forma, afea que el banco pretendiera, m\u00e1s all\u00e1 de invocar a su favor la anterior doctrina del Supremo, vigente hasta el pasado febrero y que establec\u00eda como l\u00edmite temporal para reclamar el 9 de mayo de 2013, \u00abintentar la suspensi\u00f3n de recurso y negar por completo la obligaci\u00f3n de restituci\u00f3n\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los usuarios afectados por la cl\u00e1usula suelo no deber\u00e1n pagar las costas judiciales para ir a juicio contra los bancos<\/p>\n","protected":false},"author":3,"featured_media":16514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[46,43,7563,7566,7559],"tags":[4137,209],"class_list":["post-16511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bancos","category-credito-hipotecario","category-noticias-consumo","category-noticias-sobre-el-mercado-hipotecario","category-tribunal-supremo","tag-costas-judiciales","tag-tribunal-supremo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Tribunal Supremo afea su conducta a los bancos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Tribunal Supremo afea su conducta a los bancos\" \/>\n<meta property=\"og:description\" content=\"Los usuarios afectados por la cl\u00e1usula suelo no deber\u00e1n pagar las costas judiciales para ir a juicio contra los bancos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de aquimicasa.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquimicasa.net\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-08T09:05:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-02T16:47:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Tribunal-Supremo2-e1499504462882.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Lizarraga\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Lizarraga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/\"},\"author\":{\"name\":\"Eduardo Lizarraga\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\"},\"headline\":\"El Tribunal Supremo afea su conducta a los bancos\",\"datePublished\":\"2017-07-08T09:05:18+00:00\",\"dateModified\":\"2020-04-02T16:47:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/\"},\"wordCount\":437,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Tribunal-Supremo2-e1499504462882.jpg\",\"keywords\":[\"costas judiciales\",\"Tribunal Supremo\"],\"articleSection\":[\"Bancos\",\"Cr\u00e9dito hipotecario\",\"Noticias Consumo\",\"Noticias sobre el Mercado Hipotecario\",\"Tribunal Supremo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/\",\"name\":\"El Tribunal Supremo afea su conducta a los bancos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Tribunal-Supremo2-e1499504462882.jpg\",\"datePublished\":\"2017-07-08T09:05:18+00:00\",\"dateModified\":\"2020-04-02T16:47:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Tribunal-Supremo2-e1499504462882.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Tribunal-Supremo2-e1499504462882.jpg\",\"width\":360,\"height\":243,\"caption\":\"Tribunal Supremo contra el TJUE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/economia\\\/credito-hipotecario\\\/tc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Tribunal Supremo afea su conducta a los bancos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"name\":\"Blog de aquimicasa.net\",\"description\":\"Noticias del Mundo Inmobiliario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\",\"name\":\"Blog de aquimicasa.net\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"width\":225,\"height\":225,\"caption\":\"Blog de aquimicasa.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aquimicasa.net\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/x.com\\\/EduLizarragaD\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\",\"name\":\"Eduardo Lizarraga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"caption\":\"Eduardo Lizarraga\"},\"description\":\"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net\",\"sameAs\":[\"https:\\\/\\\/www.aquimicasa.net\\\/\"],\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/author\\\/eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Tribunal Supremo afea su conducta a los bancos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/","og_locale":"es_ES","og_type":"article","og_title":"El Tribunal Supremo afea su conducta a los bancos","og_description":"Los usuarios afectados por la cl\u00e1usula suelo no deber\u00e1n pagar las costas judiciales para ir a juicio contra los bancos","og_url":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/","og_site_name":"Blog de aquimicasa.net","article_publisher":"https:\/\/www.facebook.com\/aquimicasa.net","article_published_time":"2017-07-08T09:05:18+00:00","article_modified_time":"2020-04-02T16:47:28+00:00","og_image":[{"width":360,"height":243,"url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Tribunal-Supremo2-e1499504462882.jpg","type":"image\/jpeg"}],"author":"Eduardo Lizarraga","twitter_misc":{"Escrito por":"Eduardo Lizarraga","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#article","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/"},"author":{"name":"Eduardo Lizarraga","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14"},"headline":"El Tribunal Supremo afea su conducta a los bancos","datePublished":"2017-07-08T09:05:18+00:00","dateModified":"2020-04-02T16:47:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/"},"wordCount":437,"commentCount":0,"publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Tribunal-Supremo2-e1499504462882.jpg","keywords":["costas judiciales","Tribunal Supremo"],"articleSection":["Bancos","Cr\u00e9dito hipotecario","Noticias Consumo","Noticias sobre el Mercado Hipotecario","Tribunal Supremo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/","url":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/","name":"El Tribunal Supremo afea su conducta a los bancos","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#primaryimage"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Tribunal-Supremo2-e1499504462882.jpg","datePublished":"2017-07-08T09:05:18+00:00","dateModified":"2020-04-02T16:47:28+00:00","breadcrumb":{"@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#primaryimage","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Tribunal-Supremo2-e1499504462882.jpg","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Tribunal-Supremo2-e1499504462882.jpg","width":360,"height":243,"caption":"Tribunal Supremo contra el TJUE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aquimicasa.net\/blog\/economia\/credito-hipotecario\/tc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aquimicasa.net\/blog\/"},{"@type":"ListItem","position":2,"name":"El Tribunal Supremo afea su conducta a los bancos"}]},{"@type":"WebSite","@id":"https:\/\/www.aquimicasa.net\/blog\/#website","url":"https:\/\/www.aquimicasa.net\/blog\/","name":"Blog de aquimicasa.net","description":"Noticias del Mundo Inmobiliario","publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aquimicasa.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aquimicasa.net\/blog\/#organization","name":"Blog de aquimicasa.net","url":"https:\/\/www.aquimicasa.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","width":225,"height":225,"caption":"Blog de aquimicasa.net"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aquimicasa.net","https:\/\/www.instagram.com\/","https:\/\/x.com\/EduLizarragaD","https:\/\/www.linkedin.com\/feed\/"]},{"@type":"Person","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14","name":"Eduardo Lizarraga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","caption":"Eduardo Lizarraga"},"description":"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net","sameAs":["https:\/\/www.aquimicasa.net\/"],"url":"https:\/\/www.aquimicasa.net\/blog\/author\/eduardo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Tribunal-Supremo2-e1499504462882.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/16511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/comments?post=16511"}],"version-history":[{"count":2,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/16511\/revisions"}],"predecessor-version":[{"id":16513,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/16511\/revisions\/16513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media\/16514"}],"wp:attachment":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media?parent=16511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/categories?post=16511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/tags?post=16511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}