{"id":32979,"date":"2020-06-18T08:37:44","date_gmt":"2020-06-18T06:37:44","guid":{"rendered":"https:\/\/www.aquimicasa.net\/blog\/?p=32979"},"modified":"2020-06-30T00:55:16","modified_gmt":"2020-06-29T22:55:16","slug":"el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario","status":"publish","type":"post","link":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/","title":{"rendered":"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:0px;margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p>El fin del confinamiento y la desescalada que este pr\u00f3ximo lunes podr\u00eda dejar a todo el pa\u00eds ya en la <strong>fase 3<\/strong>, mantiene en una tensa calma al sector inmobiliario. Tranquilidad alimentada tambi\u00e9n por un inesperado buen final de mayo, en el que se han cerrado operaciones que estaban paralizadas desde el inicio de la crisis, dando la sensaci\u00f3n de un \u00abaqu\u00ed no pasa nada\u00bb que no es real, porque en las primeras semanas de junio las operaciones han ca\u00eddo.<\/p>\n<p>Los datos son dispares, con algunas claras muestras de lo peor que puede llegar pasado el verano y otras que animan al optimismo.\u00a0 Y m\u00e1s que fijarnos en el desplome del mes de abril \u2013 no pod\u00eda ser de otra manera- en el que la <strong>compraventa de viviendas<\/strong> ha retrocedido un 71,3%, podemos tener en cuenta el incremento de impagos en los alquileres, que se ha triplicado el mes de mayo.<\/p>\n<p>Desde el optimismo podemos comprobar que el importe de estos <strong>alquileres<\/strong> se ha incrementado el primer trimestre \u2013con s\u00f3lo dos semanas de confinamiento- casi un 10% y el <strong>precio de la vivienda<\/strong> apenas ha cedido, porque los propietarios no est\u00e1n aceptando ofertas a la baja, esperando que la situaci\u00f3n se recupere y todo quede en un alarmismo infundado.<\/p>\n<p>El pa\u00eds vive acolchado en una falsa realidad, pero el fin de los ERTE, que llegar\u00e1 al finalizar el <strong>estado de alarma<\/strong>, puede devolvernos las colas en el INEM. Y es que adem\u00e1s, \u00a0tampoco la vaca lechera nacional\u00a0 tiene muchas expectativas de recuperaci\u00f3n este verano, ni tan siquiera va a dar para salvar los muebles en muchas zonas. Y no ser\u00e1 porque desde el Gobierno Central y los auton\u00f3micos no se est\u00e9 animando a los turistas a venir. La propia Uni\u00f3n Europea abre todas sus fronteras y anima a que vuelvan los visitantes de otros a\u00f1os, y es que con un peso medio en el <strong>PIB<\/strong> comunitario del 10%, el <strong>turismo<\/strong> da trabajo a m\u00e1s de 27 millones de personas. Pero en algunos pa\u00edses como Francia, Italia o Espa\u00f1a, el peso del sector tur\u00edstico es fundamental en la econom\u00eda. Por hacernos una idea, \u00a0en 2018, Espa\u00f1a fue el destino tur\u00edstico m\u00e1s com\u00fan en la UE para las personas que viajaron fuera de su pa\u00eds, con 301 millones de pernoctaciones en establecimientos de alojamiento tur\u00edstico, el 23 % del total de la UE. \u00bfC\u00f3mo no se va a salir al rescate?<\/p>\n<p>Pero difiere mucho la intenci\u00f3n del resultado final, y as\u00ed este verano va a ser el m\u00e1s at\u00edpico y pobre, y no s\u00f3lo tur\u00edsticamente hablando, de los que se tiene constancia. Muchos turistas se han hecho a la idea de no salir de sus pa\u00edses y los constantes rebrotes que todas las naciones afectadas est\u00e1n sufriendo, no les van a ayudar a cambiar su decisi\u00f3n. A nosotros nos ha ido bien con el confinamiento para controlar la pandemia y mal para la<strong> econom\u00eda<\/strong>,\u00a0 habr\u00e1 que ver lo que sucede ahora con fronteras abiertas y mucho devenir de la situaci\u00f3n confiado en la responsabilidad de los individuos.<\/p>\n<p>El verano marca la <strong>frontera entre la incertidumbre y la realidad<\/strong>. Algo parecido nos sucedi\u00f3 en el 2007, cuando nos fuimos de vacaciones ricos y poderosos y volvimos con la econom\u00eda saltando por los aires.<\/p>\n<p>En la <strong>compraventa de viviendas<\/strong> est\u00e1n llegando <strong>ofertas de compra<\/strong> con descuentos del\u00a0 10%, que se reducen a un 7% en las grandes ciudades, aunque siempre est\u00e1n las excepciones de los que se creen llamados a hacer el negocio de su vida y entran con descuentos del 25%. \u00a0El mercado vuelve a estar dominado por los <strong>compradores<\/strong> con liquidez, pero de momento los vendedores se mantienen firmes.<\/p>\n<p>Distinta es la situaci\u00f3n del <strong>mercado del alquiler,<\/strong> con bajadas de precios que se iniciaron nada m\u00e1s lleg\u00f3 el confinamiento y que oscilan entre el 10 y el 20%, sobre todo en alquileres elevados. Y esta situaci\u00f3n se est\u00e1 dando en un mercado que contin\u00faa, a pesar del trasvase de <strong>pisos tur\u00edsticos<\/strong> al alquiler tradicional, con un exceso de demanda para la oferta existente<span style=\"color: #ff0000;\">.<\/span> Esta es una de las partes de la ecuaci\u00f3n que no podemos dejar de tener en cuenta, sobre todo por los quebraderos de cabeza que va a proporcionar a las administraciones p\u00fablicas en los pr\u00f3ximos meses.<\/p>\n<p>Muchas voces se alzan con optimismo hablando de un mercado en U y con una recuperaci\u00f3n constante a partir del mes de julio. Y m\u00e1s pensando en los<strong> compradores extranjeros<\/strong> que tienen que volver y en <strong>inversores<\/strong> internacionales que han asegurado disponer ya de fondos de 40.000 millones para ir de compras en el inmobiliario espa\u00f1ol. Parece que no se tiene en cuenta el desastre econ\u00f3mico y laboral que este virus ha causado en nuestra sociedad y lo que a\u00fan resta.<\/p>\n<p>El quid de la situaci\u00f3n va a estar en el <strong>mercado del alquiler<\/strong> y ya se est\u00e1n moviendo los actores para que la vuelta a la cruda realidad no les pille desprevenidos. Ejemplos de inversi\u00f3n en \u201cbuild to rent\u201d, que se est\u00e1n viendo acelerados, hay muchos. Como el Grupo Qualitas Equity \u2013especializado en la gesti\u00f3n de activos alternativos\u2013 que est\u00e1 moviendo a la carrera una inversi\u00f3n de 200 millones de euros para promover 1.000<strong> viviendas de alquiler<\/strong>, mediante promociones de edificios de obra nueva con calificaci\u00f3n energ\u00e9tica A, en la <strong>Comunidad de Madrid<\/strong>.<\/p>\n<p>Tambi\u00e9n las administraciones que ven el problema venir se est\u00e1n moviendo. Como el <strong>Ayuntamiento de Madrid<\/strong> que acaba de adjudicar \u2013reba\u00f1ando restos por aqu\u00ed y all\u00e1- un paquete de 163 viviendas en alquiler. Y prepara otros para este mismo a\u00f1o, sin contar con que dispone de 38 promociones en marcha, con unos 3.200 pisos, que podr\u00e1n adjudicarse este a\u00f1o si terminan las obras y da tiempo a organizar la convocatoria. Lo que tiene asegurados son los demandantes, nada menos que 26.000 se inscribieron para el sorteo de esos 163 pisos. Buena muestra de que hace falta m\u00e1s inversi\u00f3n en alquiler social y que el patrimonio no se venda luego a fondos buitre, como pas\u00f3 con la vivienda social de la <strong>EMVS<\/strong> en el anterior consistorio de Botella, que por cierto ha quedado impune.<\/p>\n<p>Otro ejemplo que ilustra lo que viene es \u00a0<strong>Navarra<\/strong>. Donde su <strong>\u00a0Direcci\u00f3n General de Vivienda<\/strong> ha desarrollado una labor de rastreo de posibles inmuebles deshabitados en Pamplona y otras poblaciones. Se trata del primer plan piloto que tiene por objeto localizar <strong>inmuebles sin uso<\/strong> y dar respuesta al crecimiento de la demanda de viviendas de arrendamiento. Y han detectado nada menos que 2.638 inmuebles, pertenecientes a 1.860 titulares. Ya se han puesto en contacto para decirles que estos inmuebles no han tenido un uso residencial en al menos los \u00faltimos seis meses y que, en el caso de que no acrediten lo contrario ante la Inspecci\u00f3n del departamento de Vivienda, pasar\u00e1n a incluirse en el registro de viviendas vac\u00edas, como primer paso para adoptar medidas o aplicar normativa que faciliten su movilizaci\u00f3n en el <strong>mercado de alquiler<\/strong>.<\/p>\n<p>El programa puesto en marcha por la<strong> Comunidad Foral<\/strong> asegura el cobro puntual de la renta y abono de gastos de comunidad, concede una subvenci\u00f3n de 1.500 euros a la firma del contrato y devoluci\u00f3n del piso en perfecto estado al finalizar el mismo, una desgravaci\u00f3n fiscal del 40% o financiaci\u00f3n al 0% de inter\u00e9s de las reformas de adecuaci\u00f3n si fueran necesarias. <strong>Eneko Larrarte<\/strong>, director de Vivienda del<strong> Gobierno de Navarra,<\/strong> ha se\u00f1alado que \u201cesta pol\u00edtica de ocupaci\u00f3n de las <strong>viviendas vac\u00edas<\/strong> es uno de los mejores ejemplos de la estrategia puesta en marcha por el Gobierno para recuperar la funci\u00f3n social de la vivienda y su valor de uso frente a la mera consideraci\u00f3n de un bien de inversi\u00f3n\u00bb.<\/p>\n<p>Pero no s\u00f3lo empresas y administraciones se han puesto en marcha previendo lo que viene, tambi\u00e9n otras organizaciones est\u00e1n colocando la venda antes de la herida, como la <strong>Asociaci\u00f3n de Propietarios de Vivienda en Alquiler (ASVAL)<\/strong>, que\u00a0 alarmada por el aumento de los <strong>impagos en el alquiler<\/strong> y \u00a0la escasa repercusi\u00f3n que el programa de avales del ICO est\u00e1 teniendo en este problema, solicita un cambio en las ayudas del Gobierno. Habla de la vulnerabilidad de los <strong>inquilinos<\/strong> y solicita que se establezca un programa de ayudas directas a los <strong>arrendadores<\/strong> que no supongan un endeudamiento para los inquilinos. Vamos, que sus rentas se las pague el Estado. El problema aparece porque al ser un cr\u00e9dito que habr\u00e1 que devolver, muchos de los afectados, que han perdido sus trabajos y que ven complicado el futuro como para cargarse con pr\u00e9stamos, est\u00e1n renunciando a estos avales del ICO, optando inicialmente por dejar de pagar sus<strong> alquileres<\/strong> antes que aplazar el pago o fraccionar la deuda, lo que traer\u00e1 aparejado \u2013aseguran- un aumento de la litigiosidad.<\/p>\n<p>Y es este el problema que m\u00e1s temen, porque ya saben lo que nos espera tras un verano de sol y calor. No hay que ser pesimista, pero siempre conviene tener los pies en el suelo. Si las cifras de ca\u00edda del <strong>PIB<\/strong> previstas por el <strong>Banco de Espa\u00f1a<\/strong> son correctas y sabiendo por estad\u00edstica la relaci\u00f3n entre desempleo y bajada de la actividad econ\u00f3mica, podr\u00edamos estar ante un panorama de casi un mill\u00f3n de nuevos desempleados a apuntar al coronavirus. Y son los que disponen de trabajos m\u00e1s precarios y que por lo general viven de alquiler. No me extra\u00f1a que <strong>ASVAL<\/strong> quiera que las rentas de los propietarios se las paguemos entre todos.<\/p>\n<p>El Gobierno de PSOE y Podemos se va a enfrentar a m\u00faltiples problemas conforme vayan pasando los meses y la crisis econ\u00f3mica se acent\u00fae. Y uno de ellos y no el m\u00e1s peque\u00f1o, va a ser la decisi\u00f3n que tendr\u00e1 que tomar cuando aumenten los lanzamientos y el clamor contra los <strong>desahucios<\/strong> vuelva a las calles. No hay <strong>vivienda social<\/strong> para todas esas personas, van a tener que dividir los recursos y la transparencia econ\u00f3mica de los individuos y sus necesidades va a ser un objetivo de todos los Gobiernos.<\/p>\n<p>El <strong>mercado del alquiler<\/strong> y las decisiones legislativas y econ\u00f3micas que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo de todo el sector inmobiliario en los pr\u00f3ximos a\u00f1os. Inversores, rentistas, promotores, administraciones, grupos sociales\u2026 lo saben e intentar\u00e1n influir en su evoluci\u00f3n,\u00a0 el <strong>alquiler<\/strong> marcar\u00e1 las pautas.<\/p>\n<p>Como ya denunciaba el propio <strong>Banco de Espa\u00f1a<\/strong>, en el fondo del problema est\u00e1 \u00a0la escasa oferta\u00a0 de viviendas en alquiler asequible y que si ya deb\u00eda incrementarse antes del <strong>Covid-1<\/strong>9, la situaci\u00f3n se ha agravado con la pandemia. \u00bfSe movilizar\u00e1n los recursos de <strong>vivienda vac\u00eda<\/strong>? \u00bfSe pagar\u00e1n los alquileres directamente a los propietarios en un porcentaje sobre el importe? \u00bfSe establecer\u00e1 una <strong>moratoria sobre los desahucios<\/strong> en tanto dure la crisis? La primera regla de la meteorolog\u00eda dice que una tormenta no cesar\u00e1 en tanto que las causas que la originan se mantengan, y es de aplicaci\u00f3n en todas las tormentas, como la que llega al sector inmobiliario.<\/p>\n<p>Decisiones complicadas en <strong>un pa\u00eds que se ha quedado sin recursos<\/strong> y que deber\u00e1 apelar, ya lo est\u00e1 haciendo, a la solidaridad europea. Pero ya estamos viendo el talante que muestran y esperan que nuestro pa\u00eds utilice su riqueza. Lo dijo el vicepresidente Pablo Iglesias \u00a0hace unas semanas, hablando del \u00abimpuesto a los ricos\u00bb\u00a0 el <strong>Art\u00edculo 128 de nuestra Constituci\u00f3n <\/strong>confirma que<strong> \u00a0\u201c<\/strong>toda la riqueza del pa\u00eds en sus distintas formas y sea cual fuere su titularidad est\u00e1 subordinada al inter\u00e9s general. Se reconoce la iniciativa p\u00fablica en la actividad econ\u00f3mica\u201d.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-27470\" src=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Eduardo2.jpg\" alt=\"\" width=\"123\" height=\"151\" srcset=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Eduardo2-122x150.jpg 122w, https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Eduardo2-200x246.jpg 200w, https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Eduardo2-244x300.jpg 244w, https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Eduardo2-400x492.jpg 400w, https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Eduardo2.jpg 513w\" sizes=\"(max-width: 123px) 100vw, 123px\" \/><\/p>\n<p>Eduardo Lizarraga<\/p>\n<p>WWW.AQUIMICASA.NET<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El mercado del alquiler y las decisiones legislativas y econ\u00f3micas \u00a0que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo de todo el sector inmobiliario en los pr\u00f3ximos a\u00f1os. Inversores, rentistas, promotores, administraciones, grupos sociales\u2026 lo saben e intentar\u00e1n influir en su evoluci\u00f3n,\u00a0 el alquiler marcar\u00e1 las pautas.<\/p>\n","protected":false},"author":3,"featured_media":32987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3249],"tags":[2989,6402,7861,7865],"class_list":["post-32979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-articulo-de-opinion","tag-eduardo-lizarraga","tag-newsletter-258","tag-newsletter-259"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario<\/title>\n<meta name=\"description\" content=\"El alquiler y las decisiones legislativas y econ\u00f3micas \u00a0que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo del sector inmobiliario\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario\" \/>\n<meta property=\"og:description\" content=\"El alquiler y las decisiones legislativas y econ\u00f3micas \u00a0que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo del sector inmobiliario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de aquimicasa.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquimicasa.net\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-18T06:37:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T22:55:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquileres1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"470\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo Lizarraga\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Lizarraga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/\"},\"author\":{\"name\":\"Eduardo Lizarraga\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\"},\"headline\":\"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario\",\"datePublished\":\"2020-06-18T06:37:44+00:00\",\"dateModified\":\"2020-06-29T22:55:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/\"},\"wordCount\":2185,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquileres1.png\",\"keywords\":[\"art\u00edculo de opini\u00f3n\",\"Eduardo Lizarraga\",\"Newsletter 258\",\"Newsletter 259\"],\"articleSection\":[\"Opini\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/\",\"name\":\"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquileres1.png\",\"datePublished\":\"2020-06-18T06:37:44+00:00\",\"dateModified\":\"2020-06-29T22:55:16+00:00\",\"description\":\"El alquiler y las decisiones legislativas y econ\u00f3micas \u00a0que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo del sector inmobiliario\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquileres1.png\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquileres1.png\",\"width\":470,\"height\":315,\"caption\":\"La ley de Viveinda espera el fin de las vacaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/opinion\\\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"name\":\"Blog de aquimicasa.net\",\"description\":\"Noticias del Mundo Inmobiliario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\",\"name\":\"Blog de aquimicasa.net\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"width\":225,\"height\":225,\"caption\":\"Blog de aquimicasa.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aquimicasa.net\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/x.com\\\/EduLizarragaD\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\",\"name\":\"Eduardo Lizarraga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"caption\":\"Eduardo Lizarraga\"},\"description\":\"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net\",\"sameAs\":[\"https:\\\/\\\/www.aquimicasa.net\\\/\"],\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/author\\\/eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario","description":"El alquiler y las decisiones legislativas y econ\u00f3micas \u00a0que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo del sector inmobiliario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/","og_locale":"es_ES","og_type":"article","og_title":"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario","og_description":"El alquiler y las decisiones legislativas y econ\u00f3micas \u00a0que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo del sector inmobiliario","og_url":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/","og_site_name":"Blog de aquimicasa.net","article_publisher":"https:\/\/www.facebook.com\/aquimicasa.net","article_published_time":"2020-06-18T06:37:44+00:00","article_modified_time":"2020-06-29T22:55:16+00:00","og_image":[{"width":470,"height":315,"url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquileres1.png","type":"image\/png"}],"author":"Eduardo Lizarraga","twitter_misc":{"Escrito por":"Eduardo Lizarraga","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#article","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/"},"author":{"name":"Eduardo Lizarraga","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14"},"headline":"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario","datePublished":"2020-06-18T06:37:44+00:00","dateModified":"2020-06-29T22:55:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/"},"wordCount":2185,"commentCount":0,"publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquileres1.png","keywords":["art\u00edculo de opini\u00f3n","Eduardo Lizarraga","Newsletter 258","Newsletter 259"],"articleSection":["Opini\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/","url":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/","name":"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#primaryimage"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquileres1.png","datePublished":"2020-06-18T06:37:44+00:00","dateModified":"2020-06-29T22:55:16+00:00","description":"El alquiler y las decisiones legislativas y econ\u00f3micas \u00a0que se tomen en su evoluci\u00f3n, van a ser la clave que marcar\u00e1 el desarrollo del sector inmobiliario","breadcrumb":{"@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#primaryimage","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquileres1.png","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquileres1.png","width":470,"height":315,"caption":"La ley de Viveinda espera el fin de las vacaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aquimicasa.net\/blog\/opinion\/el-mercado-del-alquiler-marcara-el-desarrollo-del-sector-inmobiliario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aquimicasa.net\/blog\/"},{"@type":"ListItem","position":2,"name":"El mercado del alquiler marcar\u00e1 el desarrollo del sector inmobiliario"}]},{"@type":"WebSite","@id":"https:\/\/www.aquimicasa.net\/blog\/#website","url":"https:\/\/www.aquimicasa.net\/blog\/","name":"Blog de aquimicasa.net","description":"Noticias del Mundo Inmobiliario","publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aquimicasa.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aquimicasa.net\/blog\/#organization","name":"Blog de aquimicasa.net","url":"https:\/\/www.aquimicasa.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","width":225,"height":225,"caption":"Blog de aquimicasa.net"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aquimicasa.net","https:\/\/www.instagram.com\/","https:\/\/x.com\/EduLizarragaD","https:\/\/www.linkedin.com\/feed\/"]},{"@type":"Person","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14","name":"Eduardo Lizarraga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","caption":"Eduardo Lizarraga"},"description":"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net","sameAs":["https:\/\/www.aquimicasa.net\/"],"url":"https:\/\/www.aquimicasa.net\/blog\/author\/eduardo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquileres1.png","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/32979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/comments?post=32979"}],"version-history":[{"count":8,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/32979\/revisions"}],"predecessor-version":[{"id":32989,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/32979\/revisions\/32989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media\/32987"}],"wp:attachment":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media?parent=32979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/categories?post=32979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/tags?post=32979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}