{"id":39170,"date":"2021-12-01T16:55:39","date_gmt":"2021-12-01T15:55:39","guid":{"rendered":"https:\/\/www.aquimicasa.net\/blog\/?p=39170"},"modified":"2021-12-01T16:55:39","modified_gmt":"2021-12-01T15:55:39","slug":"las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre","status":"publish","type":"post","link":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/","title":{"rendered":"Las hipotecas inscritas se incrementan un 57,7% en septiembre"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p>Como no pod\u00eda ser menos y de manera proporcional a las operaciones sobre vivienda realizadas el pasado mes de septiembre, el mercado hipotecario tambi\u00e9n ha vivido un notable incremento. Seg\u00fan datos del Instituto Nacional de Estad\u00edstica, (INE), el n\u00famero de hipotecas sobre viviendas inscritas en los registros de la propiedad en el mes de septiembre es de 42.547, un 57,7% m\u00e1s en tasa anual. Tambi\u00e9n sube el importe medio de dichas hipotecas, que aumenta un 7,0% y se sit\u00faa en 143.831 euros.<\/p>\n<p>Si tenemos en cuenta el total de fincas inscritas en los registros de la de la propiedad en septiembre (procedentes de escrituras p\u00fablicas realizadas anteriormente) , el importe medio de las hipotecas es de 148.823 euros, un 7,8% superior al del mismo mes de 2020. Por su parte, el valor de las hipotecas constituidas sobre fincas urbanas alcanza los 8.137,1 millones de euros, un 59,4% m\u00e1s que en septiembre de 2020. En viviendas, el capital prestado se sit\u00faa en 6.119,6 millones, con un incremento anual del 68,7%. Por naturaleza de la finca, las hipotecas constituidas sobre viviendas concentran el 73,5% del capital total prestado en el mes de septiembre.<\/p>\n<p>En las hipotecas constituidas sobre viviendas, el tipo de inter\u00e9s medio es del 2,47% y el plazo medio de 25 a\u00f1os. El 34,3% de las hipotecas sobre viviendas se constituye a tipo variable y el 65,7% a tipo fijo. El tipo de inter\u00e9s medio al inicio es del 2,19% para las hipotecas sobre viviendas a tipo variable y del 2,65% para las de tipo fijo.<\/p>\n<p>El n\u00famero total de hipotecas con cambios en sus condiciones inscritas en los registros de la propiedad es de 20.247, un 140,7% m\u00e1s que en septiembre de 2020. Atendiendo a la clase de cambio en las condiciones, en septiembre se producen 16.756 novaciones (o modificaciones producidas con la misma entidad financiera), con un aumento anual del 139,4%. Por su parte, el n\u00famero de operaciones que cambian de entidad (subrogaciones al acreedor) sube un 107,8%, y el de hipotecas en las que cambia el titular del bien hipotecado (subrogaciones al deudor) un 317,8%.<\/p>\n<p>De las 20.247 hipotecas con cambios en sus condiciones, el 19,4% se deben a modificaciones en los tipos de inter\u00e9s. Despu\u00e9s del cambio de condiciones, el porcentaje de hipotecas a inter\u00e9s fijo aumenta del 21,3% al 40,5%, mientras que el de hipotecas a inter\u00e9s variable disminuye del 77,8% al 56,0%. El Euribor es el tipo al que se referencia el mayor porcentaje de hipotecas a tipo variable, tanto antes del cambio (65,2%), como despu\u00e9s (46,4%). Tras la modificaci\u00f3n de condiciones, el inter\u00e9s medio de los pr\u00e9stamos en las hipotecas a tipo fijo disminuye 0,8 puntos y el de las hipotecas a tipo variable baja 0,3 puntos.<\/p>\n<p><strong>Resultados por comunidades aut\u00f3nomas<\/strong><br \/>\nLas comunidades con mayor n\u00famero de hipotecas constituidas sobre viviendas en septiembre son Andaluc\u00eda (8.749), Comunidad de Madrid (7.930) y Catalu\u00f1a (7.073). Las comunidades en las que se presta m\u00e1s capital para la constituci\u00f3n de hipotecas sobre viviendas son Comunidad de Madrid (1.737,1 millones de euros), Catalu\u00f1a (1.150,3 millones) y Andaluc\u00eda (1.047,8 millones). Las comunidades con mayores tasas de variaci\u00f3n anuales en el capital prestado son Castilla y Le\u00f3n (81,2%), Andaluc\u00eda (80,4%) y Catalu\u00f1a (78,1%).<\/p>\n<p>Las comunidades con mayores tasas de variaci\u00f3n anual en el n\u00famero de hipotecas sobre viviendas son Castilla y Le\u00f3n (76,8%), Andaluc\u00eda (76,6%) y Catalu\u00f1a (76,0%). Por su parte, la \u00fanica comunidad con tasa de variaci\u00f3n anual negativa es Illes Balears (\u20132,1%).<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las comunidades con mayor n\u00famero de hipotecas constituidas sobre viviendas en septiembre son Andaluc\u00eda (8.749), Comunidad de Madrid (7.930) y Catalu\u00f1a (7.073). Las comunidades en las que se presta m\u00e1s capital para la constituci\u00f3n de hipotecas sobre viviendas son Comunidad de Madrid (1.737,1 millones de euros), Catalu\u00f1a (1.150,3 millones) y Andaluc\u00eda (1.047,8 millones).<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[100],"tags":[7995],"class_list":["post-39170","post","type-post","status-publish","format-standard","hentry","category-compraventa-de-viviendas","tag-newsletter-334"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las hipotecas inscritas se incrementan un 57,7% en septiembre<\/title>\n<meta name=\"description\" content=\"El n\u00famero de hipotecas sobre viviendas inscritas en los registros de la propiedad en septiembre es de 42.547, un 57,7% m\u00e1s en tasa anual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las hipotecas inscritas se incrementan un 57,7% en septiembre\" \/>\n<meta property=\"og:description\" content=\"El n\u00famero de hipotecas sobre viviendas inscritas en los registros de la propiedad en septiembre es de 42.547, un 57,7% m\u00e1s en tasa anual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de aquimicasa.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquimicasa.net\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T15:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/valoracion8-1-e1635199440746.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"233\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Lizarraga\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Lizarraga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/\"},\"author\":{\"name\":\"Eduardo Lizarraga\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\"},\"headline\":\"Las hipotecas inscritas se incrementan un 57,7% en septiembre\",\"datePublished\":\"2021-12-01T15:55:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/\"},\"wordCount\":814,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"keywords\":[\"newsletter 334\"],\"articleSection\":[\"Compra Venta\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/\",\"name\":\"Las hipotecas inscritas se incrementan un 57,7% en septiembre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\"},\"datePublished\":\"2021-12-01T15:55:39+00:00\",\"description\":\"El n\u00famero de hipotecas sobre viviendas inscritas en los registros de la propiedad en septiembre es de 42.547, un 57,7% m\u00e1s en tasa anual.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las hipotecas inscritas se incrementan un 57,7% en septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"name\":\"Blog de aquimicasa.net\",\"description\":\"Noticias del Mundo Inmobiliario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\",\"name\":\"Blog de aquimicasa.net\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"width\":225,\"height\":225,\"caption\":\"Blog de aquimicasa.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aquimicasa.net\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/x.com\\\/EduLizarragaD\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\",\"name\":\"Eduardo Lizarraga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"caption\":\"Eduardo Lizarraga\"},\"description\":\"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net\",\"sameAs\":[\"https:\\\/\\\/www.aquimicasa.net\\\/\"],\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/author\\\/eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las hipotecas inscritas se incrementan un 57,7% en septiembre","description":"El n\u00famero de hipotecas sobre viviendas inscritas en los registros de la propiedad en septiembre es de 42.547, un 57,7% m\u00e1s en tasa anual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/","og_locale":"es_ES","og_type":"article","og_title":"Las hipotecas inscritas se incrementan un 57,7% en septiembre","og_description":"El n\u00famero de hipotecas sobre viviendas inscritas en los registros de la propiedad en septiembre es de 42.547, un 57,7% m\u00e1s en tasa anual.","og_url":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/","og_site_name":"Blog de aquimicasa.net","article_publisher":"https:\/\/www.facebook.com\/aquimicasa.net","article_published_time":"2021-12-01T15:55:39+00:00","og_image":[{"width":400,"height":233,"url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/valoracion8-1-e1635199440746.jpg","type":"image\/jpeg"}],"author":"Eduardo Lizarraga","twitter_misc":{"Escrito por":"Eduardo Lizarraga","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/#article","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/"},"author":{"name":"Eduardo Lizarraga","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14"},"headline":"Las hipotecas inscritas se incrementan un 57,7% en septiembre","datePublished":"2021-12-01T15:55:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/"},"wordCount":814,"publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"keywords":["newsletter 334"],"articleSection":["Compra Venta"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/","url":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/","name":"Las hipotecas inscritas se incrementan un 57,7% en septiembre","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#website"},"datePublished":"2021-12-01T15:55:39+00:00","description":"El n\u00famero de hipotecas sobre viviendas inscritas en los registros de la propiedad en septiembre es de 42.547, un 57,7% m\u00e1s en tasa anual.","breadcrumb":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/las-hipotecas-inscritas-se-incrementan-un-577-en-septiembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aquimicasa.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Las hipotecas inscritas se incrementan un 57,7% en septiembre"}]},{"@type":"WebSite","@id":"https:\/\/www.aquimicasa.net\/blog\/#website","url":"https:\/\/www.aquimicasa.net\/blog\/","name":"Blog de aquimicasa.net","description":"Noticias del Mundo Inmobiliario","publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aquimicasa.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aquimicasa.net\/blog\/#organization","name":"Blog de aquimicasa.net","url":"https:\/\/www.aquimicasa.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","width":225,"height":225,"caption":"Blog de aquimicasa.net"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aquimicasa.net","https:\/\/www.instagram.com\/","https:\/\/x.com\/EduLizarragaD","https:\/\/www.linkedin.com\/feed\/"]},{"@type":"Person","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14","name":"Eduardo Lizarraga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","caption":"Eduardo Lizarraga"},"description":"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net","sameAs":["https:\/\/www.aquimicasa.net\/"],"url":"https:\/\/www.aquimicasa.net\/blog\/author\/eduardo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/39170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/comments?post=39170"}],"version-history":[{"count":3,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/39170\/revisions"}],"predecessor-version":[{"id":39173,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/39170\/revisions\/39173"}],"wp:attachment":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media?parent=39170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/categories?post=39170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/tags?post=39170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}