{"id":41762,"date":"2022-09-12T11:29:42","date_gmt":"2022-09-12T09:29:42","guid":{"rendered":"https:\/\/www.aquimicasa.net\/blog\/?p=41762"},"modified":"2022-09-12T11:29:42","modified_gmt":"2022-09-12T09:29:42","slug":"el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo","status":"publish","type":"post","link":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/","title":{"rendered":"El precio del alquiler de lujo sigue en alza en todo el mundo"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p>Ya sabemos que el lujo no resulta afectado en las crisis econ\u00f3mica. Ahora Savills, la firma brit\u00e1nica de consultor\u00eda, nos confirma en un informe que el alquiler de lujo en las principales ciudades del mundo sigue al alza. El alquiler de residencial <em>prime<\/em>\u00a0en las principales ciudades del mundo ha registrado un <strong>incremento del 3,1%<\/strong>\u00a0durante el primer semestre de 2022, seg\u00fan el informe Savills\u00a0<em>Prime Residential World Cities Index: Rental Growth.<\/em><\/p>\n<p>De hecho,\u00a0el precio del alquiler de lujo ha subido m\u00e1s que el de compra\u00a0de este tipo de vivienda\u00a0<em>premium<\/em>, con una subida del 3,1% de media del residencial en alquiler frente al<strong> 2,4% de incremento en el precio de compra<\/strong>.<\/p>\n<p>Son las ciudades norteamericanas, que viven un intenso boom inmobiliario, las que se sit\u00faan en las 30 primeras posiciones de la tabla. <strong>Nueva York y Singapur<\/strong> (ambas con un repunte del 8,5%), Londres (7,7%) y Los \u00c1ngeles (5,5%) lideraron el crecimiento con un aumento superior al 5%, impulsado especialmente por la recuperaci\u00f3n de los viajes internacionales. Savills, tambi\u00e9n destaca que a pesar de la tendencia en Estados Unidos de emigrar a ciudades m\u00e1s peque\u00f1as, sobre todo en el sector tecnol\u00f3gico, la Gran Manzana sigue registrando una potente demanda.<\/p>\n<p>Los precios del alquiler marcaron<strong> r\u00e9cord en Nueva York<\/strong>, impulsados por la escasez de oferta y la demanda de espacios m\u00e1s amplios por los que los inquilinos est\u00e1n dispuestos a pagar un coste a adicional.<\/p>\n<p>En otras ciudades como <strong>Lisboa (7,6%), Miami (5,8%) y Dub\u00e1i (5,3%), el alquiler ha crecido tambi\u00e9n superando el 5%<\/strong>. El incremento en estas ciudades, explica la consultora, ha sido alentado por las nuevas tendencias de estilo de vida y con m\u00e1s superficie a disfrutar. Savills destaca que la demanda de residencias <em>prime<\/em>\u00a0en la capital portuguesa sigue teniendo un buen comportamiento, con inquilinos atra\u00eddos por una ubicaci\u00f3n global comparativamente asequible que ofrece una alta calidad de vida, m\u00e1s espacio y menor coste de la vida.<\/p>\n<p>Por el contrario, las ciudades asi\u00e1ticas como Hong Kong (-1,3%), Shenzhen (-0,7%) y Hangzhou (0,1%) registraron unos resultados negativos m\u00e1s moderados, ya que todav\u00eda tienen que hacer frente a los <strong>retos relacionados con el Covid-19<\/strong>, seg\u00fan Savills.<\/p>\n<p>En el primer semestre de 2022,\u00a0la rentabilidad bruta media de las treinta ciudades dentro analizadas por Savills se mantuvo en el 3%. Dub\u00e1i, Nueva York y Los \u00c1ngeles fueron las ciudades que ofrecieron un mayor rendimiento, al situarse la rentabilidad media por encima del 4,5%.<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entre las ciudades que van en cabeza destacan las norteamericanas, con Nueva York con un 8,5% , lo mismo que Singapur, Londres (7,7%) y Los \u00c1ngeles (5,5%). Todas ellas lideran el crecimiento con un aumento superior al 5%, impulsado especialmente por la recuperaci\u00f3n de los viajes internacionales.<\/p>\n","protected":false},"author":3,"featured_media":40465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[120,100,7565],"tags":[8051],"class_list":["post-41762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alquileres","category-compraventa-de-viviendas","category-noticias-mercado-inmobiliario","tag-newsletter-374"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El precio del alquiler de lujo sigue en alza en todo el mundo<\/title>\n<meta name=\"description\" content=\"El alquiler de residencial\u00a0prime\u00a0en las principales ciudades ha registrado un incremento del 3,1%\u00a0durante el primer semestre de 2022\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El precio del alquiler de lujo sigue en alza en todo el mundo\" \/>\n<meta property=\"og:description\" content=\"El alquiler de residencial\u00a0prime\u00a0en las principales ciudades ha registrado un incremento del 3,1%\u00a0durante el primer semestre de 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de aquimicasa.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquimicasa.net\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-12T09:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquiler-turistico4-e1649801491599.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Lizarraga\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Lizarraga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/\"},\"author\":{\"name\":\"Eduardo Lizarraga\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\"},\"headline\":\"El precio del alquiler de lujo sigue en alza en todo el mundo\",\"datePublished\":\"2022-09-12T09:29:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/\"},\"wordCount\":665,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquiler-turistico4-e1649801491599.jpg\",\"keywords\":[\"newsletter 374\"],\"articleSection\":[\"Alquiler\",\"Compra Venta\",\"Noticias Mercado Inmobiliario\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/\",\"name\":\"El precio del alquiler de lujo sigue en alza en todo el mundo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquiler-turistico4-e1649801491599.jpg\",\"datePublished\":\"2022-09-12T09:29:42+00:00\",\"description\":\"El alquiler de residencial\u00a0prime\u00a0en las principales ciudades ha registrado un incremento del 3,1%\u00a0durante el primer semestre de 2022\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquiler-turistico4-e1649801491599.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Alquiler-turistico4-e1649801491599.jpg\",\"width\":400,\"height\":251,\"caption\":\"La vivienda de lujo sube imparable\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/vivienda\\\/compraventa-de-viviendas\\\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El precio del alquiler de lujo sigue en alza en todo el mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"name\":\"Blog de aquimicasa.net\",\"description\":\"Noticias del Mundo Inmobiliario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\",\"name\":\"Blog de aquimicasa.net\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"width\":225,\"height\":225,\"caption\":\"Blog de aquimicasa.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aquimicasa.net\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/x.com\\\/EduLizarragaD\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\",\"name\":\"Eduardo Lizarraga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"caption\":\"Eduardo Lizarraga\"},\"description\":\"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net\",\"sameAs\":[\"https:\\\/\\\/www.aquimicasa.net\\\/\"],\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/author\\\/eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El precio del alquiler de lujo sigue en alza en todo el mundo","description":"El alquiler de residencial\u00a0prime\u00a0en las principales ciudades ha registrado un incremento del 3,1%\u00a0durante el primer semestre de 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/","og_locale":"es_ES","og_type":"article","og_title":"El precio del alquiler de lujo sigue en alza en todo el mundo","og_description":"El alquiler de residencial\u00a0prime\u00a0en las principales ciudades ha registrado un incremento del 3,1%\u00a0durante el primer semestre de 2022","og_url":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/","og_site_name":"Blog de aquimicasa.net","article_publisher":"https:\/\/www.facebook.com\/aquimicasa.net","article_published_time":"2022-09-12T09:29:42+00:00","og_image":[{"width":400,"height":251,"url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquiler-turistico4-e1649801491599.jpg","type":"image\/jpeg"}],"author":"Eduardo Lizarraga","twitter_misc":{"Escrito por":"Eduardo Lizarraga","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/#article","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/"},"author":{"name":"Eduardo Lizarraga","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14"},"headline":"El precio del alquiler de lujo sigue en alza en todo el mundo","datePublished":"2022-09-12T09:29:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/"},"wordCount":665,"publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquiler-turistico4-e1649801491599.jpg","keywords":["newsletter 374"],"articleSection":["Alquiler","Compra Venta","Noticias Mercado Inmobiliario"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/","url":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/","name":"El precio del alquiler de lujo sigue en alza en todo el mundo","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/#primaryimage"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquiler-turistico4-e1649801491599.jpg","datePublished":"2022-09-12T09:29:42+00:00","description":"El alquiler de residencial\u00a0prime\u00a0en las principales ciudades ha registrado un incremento del 3,1%\u00a0durante el primer semestre de 2022","breadcrumb":{"@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/#primaryimage","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquiler-turistico4-e1649801491599.jpg","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquiler-turistico4-e1649801491599.jpg","width":400,"height":251,"caption":"La vivienda de lujo sube imparable"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aquimicasa.net\/blog\/vivienda\/compraventa-de-viviendas\/el-precio-del-alquiler-de-lujo-sigue-en-alza-en-todo-el-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aquimicasa.net\/blog\/"},{"@type":"ListItem","position":2,"name":"El precio del alquiler de lujo sigue en alza en todo el mundo"}]},{"@type":"WebSite","@id":"https:\/\/www.aquimicasa.net\/blog\/#website","url":"https:\/\/www.aquimicasa.net\/blog\/","name":"Blog de aquimicasa.net","description":"Noticias del Mundo Inmobiliario","publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aquimicasa.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aquimicasa.net\/blog\/#organization","name":"Blog de aquimicasa.net","url":"https:\/\/www.aquimicasa.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","width":225,"height":225,"caption":"Blog de aquimicasa.net"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aquimicasa.net","https:\/\/www.instagram.com\/","https:\/\/x.com\/EduLizarragaD","https:\/\/www.linkedin.com\/feed\/"]},{"@type":"Person","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14","name":"Eduardo Lizarraga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","caption":"Eduardo Lizarraga"},"description":"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net","sameAs":["https:\/\/www.aquimicasa.net\/"],"url":"https:\/\/www.aquimicasa.net\/blog\/author\/eduardo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Alquiler-turistico4-e1649801491599.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/41762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/comments?post=41762"}],"version-history":[{"count":3,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/41762\/revisions"}],"predecessor-version":[{"id":41885,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/41762\/revisions\/41885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media\/40465"}],"wp:attachment":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media?parent=41762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/categories?post=41762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/tags?post=41762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}