{"id":45515,"date":"2023-10-01T22:24:45","date_gmt":"2023-10-01T20:24:45","guid":{"rendered":"https:\/\/www.aquimicasa.net\/blog\/?p=45515"},"modified":"2023-10-01T22:24:45","modified_gmt":"2023-10-01T20:24:45","slug":"los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu","status":"publish","type":"post","link":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/","title":{"rendered":"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p class=\"Standard\">Un a\u00f1o m\u00e1s, la <strong>Organizaci\u00f3n de Consumidores y Usuarios (OCU)<\/strong> ha llevado a cabo su estudio de supermercados, que pretende ser una herramienta que permite a los consumidores<strong> ahorrar de media 1.056 \u20ac<\/strong> en la cesta de la compra al comprar en el establecimiento m\u00e1s barato.<\/p>\n<p class=\"Standard\"><span class=\"Fuentedeprrafopredeter1\">Para la elaboraci\u00f3n de su estudio OCU ha visitado<strong> 1.108 establecimientos en 65 ciudades<\/strong>, adem\u00e1s de los supermercados online. En su visita OCU ha recabado 155.489 precios de una \u201ccesta de la compra\u201d compuesta por 236 productos de 16 categor\u00edas diferentes que incluyen alimentaci\u00f3n fresca (frutas, verduras, carne y pescado), alimentaci\u00f3n envasada, productos de higiene y droguer\u00eda tanto de marcas l\u00edderes de fabricante como de marcas blancas.\u00a0 <\/span><\/p>\n<h2 class=\"Standard\"><strong><span class=\"Fuentedeprrafopredeter1\">Comparaci\u00f3n de precios sencilla y r\u00e1pida entre establecimientos<\/span><\/strong><\/h2>\n<p class=\"Standard\">Con estos datos y con el objetivo de facilitar la comparaci\u00f3n entre los distintos establecimientos y poder elegir el m\u00e1s barato, OCU elabora un \u00edndice con los precios recogidos en los diferentes establecimientos, ponderados de acuerdo con el peso de cada producto en el gasto de las familias. Este \u00edndice permite de forma sencilla y r\u00e1pida comparar el nivel de precios de un establecimiento en particular, una cadena, una ciudad o una comunidad aut\u00f3noma. Se trata de una herramienta \u00fatil pensada para facilitar el ahorro en los hogares que OCU pone a disposici\u00f3n de los consumidores desde 1.988.<\/p>\n<h2 class=\"Standard\"><strong>Contin\u00faan las fuertes subidas de precios en la alimentaci\u00f3n<\/strong><\/h2>\n<p class=\"Standard\"><strong>\u00a0<\/strong>Los productos que componen la cesta OCU han visto<strong> incrementado su precio en un 14,1% de media<\/strong> desde el \u00faltimo estudio. Se trata de una subida algo menor de la experimentada el a\u00f1o pasado que fue del 15,4%. Aun as\u00ed, es la segunda mayor subida de precios en los 35 a\u00f1os del estudio de OCU. En los dos \u00faltimos a\u00f1os <strong>la subida acumulada en la cesta de la compra es del 30,8%<\/strong>, lo que ha impactado profundamente en los h\u00e1bitos de compra de los consumidores.<\/p>\n<p class=\"Standard\">Al igual que el a\u00f1o pasado afecta al 90% de los 236 productos que componen la cesta. Es una subida m\u00e1s homog\u00e9nea y con m\u00e1s tipos de productos entre las grandes subidas que las del a\u00f1o pasado. Suben con fuerza el az\u00facar 65,7%, la leche condensada (61,4%) las zanahorias (56,1%) y las patatas fritas congeladas (49,7%). Entre los pocos productos que bajan, est\u00e1 a la cabeza el aceite de girasol (-39.8%), los pl\u00e1tanos de Canarias (-34,8%), las maquinillas desechables (-22%) y el queso fresco (-21,2%). <strong>Las subidas son m\u00e1s acusadas en los productos elaborados<\/strong> y algo menos acusadas en los frescos, un sector en el que fueron algo m\u00e1s frecuentes las pocas bajadas de precios registradas.<\/p>\n<p class=\"Standard\">La subida del nivel de precios <strong>afecta a todos los supermercados<\/strong>; sin embargo, no todas las cadenas la han trasladado con la misma intensidad. De acuerdo con los datos del estudio, dentro de las grandes cadenas <strong>E. Leclerc (16,8%) Supeco (15,8%), Carrefour Express (15,3%) y BM Urban (15,1%) son las cadenas que m\u00e1s suben<\/strong>. Por el contrario, Eroski City (8,8%) Eroski (8,1%) y la cadena Masymas (8%) son las que menos suben.<\/p>\n<p class=\"Standard\">OCU advierte que el gasto en alimentaci\u00f3n ha crecido de forma importante tras dos a\u00f1os consecutivos de fuertes subidas de precios. Sin embargo, ese aumento del gasto ha venido acompa\u00f1ado de una p\u00e9rdida de poder adquisitivo, ya que comprar la misma cesta implica destinar un mayor porcentaje del presupuesto familiar. Ante esto, muchos hogares se han visto obligados a <strong>comprar m\u00e1s productos elaborados y menos productos frescos<\/strong>, de modo que la calidad nutricional de nuestra dieta se ha reducido<\/p>\n<h2 class=\"Standard\"><strong>Una buena compra permite un ahorro de 1.056 \u20ac en la cesta de la compra<\/strong><\/h2>\n<p class=\"Standard\">El estudio de OCU demuestra cada a\u00f1o que <strong>es posible ahorrar en la cesta de la compra<\/strong>. El ahorro medio nacional alcanza este a\u00f1o los 1.056 \u20ac. Ha crecido un 6,2 % con respecto al pasado, debido al mayor gasto de las familias por la subida de precios, que ha prevalecido frente a la mayor homogeneidad entre establecimientos. Han subido en mayor proporci\u00f3n los baratos que los caros, lo que ha acortado la distancia entre ellos. OCU recuerda que <strong>este ahorro medio, supone un 17,5% del presupuesto<\/strong>\u00a0que un hogar medio destina a la cesta de la compra. OCU se\u00f1ala que, en tiempos de una elevada inflaci\u00f3n y p\u00e9rdida de poder adquisitivo para los consumidores, la \u00fanica forma de hacerle frente es comprar en el establecimiento m\u00e1s barato.<\/p>\n<p class=\"Standard\">Sin embargo, no todos los consumidores tienen esta posibilidad. OCU advierte que hay <strong>notables diferencias entre ciudades<\/strong> debido a la mayor o menor amplitud y diversidad de oferta, y no tanto con el nivel de precios. El m\u00e1ximo ahorro posible se puede conseguir en Madrid donde alcanza los 3.928,43 \u20ac. Le siguen, Gij\u00f3n (1.871,1\u20ac) Valencia (1.814,98 \u20ac) y Zaragoza (1.773,32 \u20ac). Por el contrario, los ciudadanos de Cuenca son los que menos posibilidad de ahorro tienen , ya que la diferencia entre el establecimiento m\u00e1s caro y el m\u00e1s barato en su ciudad solo es de 430,25\u20ac, le siguen Puertollano (507,2 \u20ac) y Cartagena (507,82 \u20ac).<\/p>\n<h2 class=\"Standard\"><strong>Grandes diferencias de precios entre ciudades y establecimientos<\/strong><\/h2>\n<p class=\"Standard\">De nuevo el estudio de supermercados de OCU pone de manifiesto las <strong>grandes diferencias de precios entre establecimientos<\/strong>. Los m\u00e1s baratos visitados por OCU han sido el <strong>hipermercado Alcampo de Coia en Vigo y el hipermercado Alcampo de Murci<\/strong>a. A continuaci\u00f3n, se sit\u00faan 5 hipermercados m\u00e1s de la misma cadena, situados en Vigo, Castell\u00f3n, Teruel, Valencia y Gij\u00f3n. El primer establecimiento que no pertenece a esta cadena es el supermercado Dani situado en la plaza Poeta Garcilaso de Granada. Los establecimientos m\u00e1s caros visitados por OCU son dos establecimientos de la cadena <strong>S\u00e1nchez Romero<\/strong>, situados en la calle Arturo Soria y\u00a0en la calle Castell\u00f3\u00a0de Madrid.<\/p>\n<p class=\"Standard\">Para aquellos consumidores que no viven en las ciudades visitadas, OCU confecciona un \u00edndice de cadenas que permite conocer el nivel de precios de los establecimientos m\u00e1s cercanos. De acuerdo con este \u00edndice <strong>las cadenas m\u00e1s baratas son Dani y M\u00e1s Ahorro<\/strong>. A nivel nacional las cadenas m\u00e1s baratas son Family Cash y Alcampo. Por el contrario, Coaliment, El Economato, Amazon y S\u00e1nchez Romero son las cadenas m\u00e1s caras.<\/p>\n<p class=\"Standard\">El estudio de OCU recoge la disparidad en el coste de la cesta de la compra que existe entre ciudades y comunidades aut\u00f3nomas. <strong>Teruel y C\u00f3rdoba son las ciudades m\u00e1s baratas<\/strong> del estudio con un \u00edndice 100. Le siguen Jerez de la Frontera, Ciudad Real, Burgos, Castell\u00f3n, Puertollano, Vigo, Lugo, Zamora, C\u00e1diz, Cuenca y Palencia (101). <strong>Las ciudades m\u00e1s caras son Palma de Mallorca, Getxo, Madrid y Las Palmas de Gran Canaria<\/strong>. La Rioja, Galicia y Murcia son las comunidades aut\u00f3nomas m\u00e1s baratas mientras que Canarias y Baleares son aquellas donde sale m\u00e1s caro de media hacer la compra.<\/p>\n<h2><strong>Apmpliar la reducci\u00f3n del IVA a la carne y los pescados<\/strong><\/h2>\n<p class=\"Standard\">El estudio de OCU constata la importante subida de precios de la cesta de la compra que resulta especialmente perjudicial para las familias con menos recursos. Por ello OCU insiste y <strong>pide al Gobierno que amplie la reducci\u00f3n del IVA a la carne y el pescad<\/strong>o y sobre todo aumente la cuant\u00eda y el n\u00famero de beneficiarios del cheque de alimentos vigente en la actualidad. Adem\u00e1s, OCU pide a la CNMC y al Ministerio de Agricultura que intensifiquen los <strong>controles sobre la cadena alimentaria<\/strong> para vigilar que funciona correctamente y no se llevan a cabo pr\u00e1cticas especulativas que perjudican a los consumidores.<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para la elaboraci\u00f3n de su estudio OCU ha visitado 1.108 establecimientos en 65 ciudades, adem\u00e1s de los supermercados online. En su visita OCU ha recabado 155.489 precios de una \u201ccesta de la compra\u201d compuesta por 236 productos de 16 categor\u00edas diferentes que incluyen alimentaci\u00f3n fresca (frutas, verduras, carne y pescado), alimentaci\u00f3n envasada, productos de higiene y droguer\u00eda tanto de marcas l\u00edderes de fabricante como de marcas blancas.<\/p>\n","protected":false},"author":3,"featured_media":44560,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7512],"tags":[1250,8131,7568],"class_list":["post-45515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consumidores","tag-inflacion","tag-newsletter-429","tag-noticia-de-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU<\/title>\n<meta name=\"description\" content=\"El ahorro medio de 1.056 euros supone un 17,5% del presupuesto\u00a0que un hogar medio destina a la cesta de la compra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU\" \/>\n<meta property=\"og:description\" content=\"El ahorro medio de 1.056 euros supone un 17,5% del presupuesto\u00a0que un hogar medio destina a la cesta de la compra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de aquimicasa.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquimicasa.net\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-01T20:24:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Lizarraga\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Lizarraga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/\"},\"author\":{\"name\":\"Eduardo Lizarraga\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\"},\"headline\":\"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU\",\"datePublished\":\"2023-10-01T20:24:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/\"},\"wordCount\":1507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"keywords\":[\"inflaci\u00f3n\",\"newsletter 429\",\"noticia de portada\"],\"articleSection\":[\"Consumidores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/\",\"name\":\"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"datePublished\":\"2023-10-01T20:24:45+00:00\",\"description\":\"El ahorro medio de 1.056 euros supone un 17,5% del presupuesto\u00a0que un hogar medio destina a la cesta de la compra.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"width\":400,\"height\":304,\"caption\":\"Las subidas de la alimentaci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/consumidores\\\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"name\":\"Blog de aquimicasa.net\",\"description\":\"Noticias del Mundo Inmobiliario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\",\"name\":\"Blog de aquimicasa.net\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"width\":225,\"height\":225,\"caption\":\"Blog de aquimicasa.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aquimicasa.net\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/x.com\\\/EduLizarragaD\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\",\"name\":\"Eduardo Lizarraga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"caption\":\"Eduardo Lizarraga\"},\"description\":\"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net\",\"sameAs\":[\"https:\\\/\\\/www.aquimicasa.net\\\/\"],\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/author\\\/eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU","description":"El ahorro medio de 1.056 euros supone un 17,5% del presupuesto\u00a0que un hogar medio destina a la cesta de la compra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/","og_locale":"es_ES","og_type":"article","og_title":"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU","og_description":"El ahorro medio de 1.056 euros supone un 17,5% del presupuesto\u00a0que un hogar medio destina a la cesta de la compra.","og_url":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/","og_site_name":"Blog de aquimicasa.net","article_publisher":"https:\/\/www.facebook.com\/aquimicasa.net","article_published_time":"2023-10-01T20:24:45+00:00","og_image":[{"width":400,"height":304,"url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","type":"image\/jpeg"}],"author":"Eduardo Lizarraga","twitter_misc":{"Escrito por":"Eduardo Lizarraga","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#article","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/"},"author":{"name":"Eduardo Lizarraga","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14"},"headline":"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU","datePublished":"2023-10-01T20:24:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/"},"wordCount":1507,"commentCount":0,"publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","keywords":["inflaci\u00f3n","newsletter 429","noticia de portada"],"articleSection":["Consumidores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/","url":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/","name":"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#primaryimage"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","datePublished":"2023-10-01T20:24:45+00:00","description":"El ahorro medio de 1.056 euros supone un 17,5% del presupuesto\u00a0que un hogar medio destina a la cesta de la compra.","breadcrumb":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#primaryimage","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","width":400,"height":304,"caption":"Las subidas de la alimentaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/consumidores\/los-alimentos-suben-un-14-1-en-un-ano-segun-la-ocu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aquimicasa.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Los alimentos suben un 14.1% en un a\u00f1o, seg\u00fan la OCU"}]},{"@type":"WebSite","@id":"https:\/\/www.aquimicasa.net\/blog\/#website","url":"https:\/\/www.aquimicasa.net\/blog\/","name":"Blog de aquimicasa.net","description":"Noticias del Mundo Inmobiliario","publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aquimicasa.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aquimicasa.net\/blog\/#organization","name":"Blog de aquimicasa.net","url":"https:\/\/www.aquimicasa.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","width":225,"height":225,"caption":"Blog de aquimicasa.net"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aquimicasa.net","https:\/\/www.instagram.com\/","https:\/\/x.com\/EduLizarragaD","https:\/\/www.linkedin.com\/feed\/"]},{"@type":"Person","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14","name":"Eduardo Lizarraga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","caption":"Eduardo Lizarraga"},"description":"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net","sameAs":["https:\/\/www.aquimicasa.net\/"],"url":"https:\/\/www.aquimicasa.net\/blog\/author\/eduardo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/45515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/comments?post=45515"}],"version-history":[{"count":3,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/45515\/revisions"}],"predecessor-version":[{"id":45528,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/45515\/revisions\/45528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media\/44560"}],"wp:attachment":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media?parent=45515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/categories?post=45515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/tags?post=45515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}