{"id":45758,"date":"2023-10-28T20:19:09","date_gmt":"2023-10-28T18:19:09","guid":{"rendered":"https:\/\/www.aquimicasa.net\/blog\/?p=45758"},"modified":"2023-10-28T20:19:09","modified_gmt":"2023-10-28T18:19:09","slug":"humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion","status":"publish","type":"post","link":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/","title":{"rendered":"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p>No se ha llegado todav\u00eda a un acuerdo para conseguir que la votaci\u00f3n en el Congreso de a S\u00e1nchez una mayor\u00eda absoluta y ya est\u00e1n Sumar y el PSOE llegando a acuerdos de gobierno; mucha prisa tiene Yolanda por asegurarse una posici\u00f3n que las encuestas le est\u00e1n rebajando.\u00a0 Entre otras cosas, han trascendido las medidas que ambos partidos tomar\u00e1n para combatir el encarecimiento de los alimentos, que contin\u00faa siendo una pesadilla cada vez que se entra en el supermercado a hacer la compra. Lo dice Rub\u00e9n S\u00e1nchez, Secretario General de FACUA, tachando las medidas de \u00abhumo\u00bb. Pero creo que en esta ocasi\u00f3n se queda algo corto y creo que las medidas anunciadas son <strong>una burla para aquello a los que les falta sueldo para comer<\/strong>.<\/p>\n<h2><strong>Humo y danza para bajar los precios de la alimentaci\u00f3n<\/strong><\/h2>\n<p>Y vayamos acostumbr\u00e1ndonos, porque una gran vendedora de humo, acomodada a la conveniencia del PSOE, puede ser Yolanda D\u00edaz, que quiere transformar a la izquierda que surgi\u00f3 del 11 M en <strong>animalito dom\u00e9stico, servil, complaciente y desactivado<\/strong>. Y el humo que nos quiere vender, ayudar\u00e1 tambi\u00e9n a esconder detr\u00e1s a los verdaderos causantes de la carest\u00eda alimenticia y de una parte de la inflaci\u00f3n, uno de ellos, la tercera fortuna de Espa\u00f1a y que de momento no ve fiscalizados ni controlados sus beneficios. Todo lo contrario, se anuncia <strong>dinero p\u00fablico<\/strong> para que los m\u00e1s desfavorecidos sigan engordando los bolsillos de los Roig y compa\u00f1\u00eda.<\/p>\n<p>Nos dice Rub\u00e9n S\u00e1nchez que el reci\u00e9n anunciado acuerdo para un gobierno de coalici\u00f3n firmado por PSOE y Sumar incluye medidas para <strong>\u00abcombatir\u00bb el encarecimiento de los alimentos<\/strong> y para contribuir a que <em>\u00abtodas las familias\u00bb<\/em>\u00a0puedan\u00a0<em>\u00abdisponer de una cesta de la compra a precios asequibles\u00bb<\/em>. Mensajes que pueden usarse con grandilocuencia en los discursos de los dirigentes de ambas formaciones, que pueden dar lugar a llamativos titulares de prensa y que pueden provocar grandes expectativas entre los consumidores. El problema es que <strong>las promesas no son m\u00e1s que humo<\/strong>.<\/p>\n<p>El punto del acuerdo PSOE-Sumar que habla de los precios de los alimentos anuncia un sistema<em>\u00a0\u00abque contribuya a disponer de una cesta de la compra b\u00e1sica a precios asequibles, variada y de calidad, que permita el acceso de todas las familias a bienes esenciales y, a la vez, contribuya al objetivo de contenci\u00f3n de la inflaci\u00f3n\u00bb<\/em>.<\/p>\n<p><strong>Los precios de los alimentos bajar\u00e1n a golpe de informe<\/strong><\/p>\n<p>\u00bfC\u00f3mo pretenden lograr todo esto? Mediante\u00a0<em>\u00abu<strong>n sistema de seguimiento, informaci\u00f3n y evaluaci\u00f3n de los precios de los alimentos b\u00e1sicos<\/strong>\u00ab<\/em>. S\u00ed, solo eso. Dicen que van a conseguir que los consumidores dispongan de alimentos b\u00e1sicos variados y de calidad a precios asequibles a base de indagar en la evoluci\u00f3n de los precios, informar de la evoluci\u00f3n de esos precios y evaluar c\u00f3mo evolucionan esos precios.<\/p>\n<p>Ese punto del acuerdo no incluye ni una sola palabra que sugiera medida alguna para <strong>intervenir en los m\u00e1rgenes de beneficio de la industria alimentaria y las grandes cadenas de distribuci\u00f3n.<\/strong> Es como prometer que traer\u00e1s la lluvia mirando fijamente a las nubes. O haci\u00e9ndoles un baile\u2026 De momento, lo que han hecho desde el Gobierno saliente con los empresarios que se est\u00e1n forrando a lo grande con sus subidas de precios ha sido bailarles el agua justificando que suben porque no tienen m\u00e1s remedio o, como mucho, criticarlos flojito. Diciendo lo grave que resulta que suban los precios pero <strong>sin actuar para que dejen de hacerlo<\/strong>. No est\u00e1 bien ni como broma.<\/p>\n<h2><strong>Se renunci\u00f3 al IVA y ahora se dedicar\u00e1 dinero p\u00fablico a los causantes de los precios<\/strong><\/h2>\n<p>El Gobierno que est\u00e1 por llegar \u2014si les salen los n\u00fameros en la investidura\u2014 habla ahora de\u00a0<em>\u00abcombatir\u00bb\u00a0<\/em>el encarecimiento de los alimentos. Pero ese supuesto combate <strong>no ser\u00e1 a base de fijar topes a los precios<\/strong>. Ni tan siquiera hablan de prorrogar la prohibici\u00f3n de aumentar los m\u00e1rgenes de beneficio en los alimentos b\u00e1sicos afectados por la bajada del IVA. A fin de cuentas, se han desentendido de tomar medidas contra las empresas que se han saltado esa prohibici\u00f3n.<\/p>\n<p>Ese supuesto combate contra la inflaci\u00f3n consistir\u00e1 en <strong>desarrollar una pol\u00edtica pasiva y meramente contemplativa<\/strong> ante lo que ocurra con los precios. Y en destinar dinero p\u00fablico para paliar un poquito los efectos de las subidas en un peque\u00f1o porcentaje de familias.<\/p>\n<p>Si durante 2023 se ha renunciado a recaudar una ingente cantidad de dinero para las arcas p\u00fablicas a trav\u00e9s de la <strong>bajada del IVA<\/strong>, lo siguiente ser\u00e1 otorgar\u00a0<em>\u00abayudas directas focalizadas para las familias m\u00e1s vulnerables\u00bb<\/em>. As\u00ed reza el texto del acuerdo de coalici\u00f3n. Un acuerdo que se limita a <strong>rezarle al mercado<\/strong>. Solo eso y nada m\u00e1s que eso. De\u00a0<em>\u00abcombatir\u00bb\u00a0<\/em>contra los grandes empresarios que llevan a\u00f1os inflando sus m\u00e1rgenes de beneficio, nada de nada. Que tampoco es plan de molestar a los multimillonarios que nos est\u00e1n empobreciendo cada vez m\u00e1s.<\/p>\n<p>Es el editorial del poscast de<strong> Rub\u00e9n S\u00e1nchez<\/strong> que en ocasiones ve fraudes.<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si durante 2023 se ha renunciado a recaudar una ingente cantidad de dinero para las arcas p\u00fablicas a trav\u00e9s de la bajada del IVA, lo siguiente ser\u00e1 otorgar\u00a0\u00abayudas directas focalizadas para las familias m\u00e1s vulnerables\u00bb. As\u00ed reza el texto del acuerdo de coalici\u00f3n. Un acuerdo que se limita a rezarle al mercado. Solo eso y nada m\u00e1s que eso. De\u00a0\u00abcombatir\u00bb\u00a0contra los grandes empresarios que llevan a\u00f1os inflando sus m\u00e1rgenes de beneficio, nada de nada. Que tampoco es plan de molestar a los multimillonarios que nos est\u00e1n empobreciendo cada vez m\u00e1s.<\/p>\n","protected":false},"author":3,"featured_media":44560,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[641],"tags":[1250,8135,7568],"class_list":["post-45758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asociacion-de-consumidores","tag-inflacion","tag-newsletter-433","tag-noticia-de-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Se pretende lograr precios asequibles mediante\u00a0un sistema de seguimiento, informaci\u00f3n y evaluaci\u00f3n de los precios de los alimentos b\u00e1sicos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Se pretende lograr precios asequibles mediante\u00a0un sistema de seguimiento, informaci\u00f3n y evaluaci\u00f3n de los precios de los alimentos b\u00e1sicos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de aquimicasa.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquimicasa.net\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-28T18:19:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Lizarraga\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Lizarraga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/\"},\"author\":{\"name\":\"Eduardo Lizarraga\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\"},\"headline\":\"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n\",\"datePublished\":\"2023-10-28T18:19:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/\"},\"wordCount\":1134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"keywords\":[\"inflaci\u00f3n\",\"newsletter 433\",\"noticia de portada\"],\"articleSection\":[\"Asociaciones de Consumidores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/\",\"name\":\"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"datePublished\":\"2023-10-28T18:19:09+00:00\",\"description\":\"Se pretende lograr precios asequibles mediante\u00a0un sistema de seguimiento, informaci\u00f3n y evaluaci\u00f3n de los precios de los alimentos b\u00e1sicos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/alimentacion3-e1687039563133.jpg\",\"width\":400,\"height\":304,\"caption\":\"Las subidas de la alimentaci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/consumo\\\/asociacion-de-consumidores\\\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"name\":\"Blog de aquimicasa.net\",\"description\":\"Noticias del Mundo Inmobiliario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#organization\",\"name\":\"Blog de aquimicasa.net\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"contentUrl\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/wp-content\\\/uploads\\\/Logo-aquimicasa-1-e1528048213782.png\",\"width\":225,\"height\":225,\"caption\":\"Blog de aquimicasa.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aquimicasa.net\",\"https:\\\/\\\/www.instagram.com\\\/\",\"https:\\\/\\\/x.com\\\/EduLizarragaD\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/#\\\/schema\\\/person\\\/2cdfa2605534583395c8d7ce1d6cac14\",\"name\":\"Eduardo Lizarraga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g\",\"caption\":\"Eduardo Lizarraga\"},\"description\":\"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net\",\"sameAs\":[\"https:\\\/\\\/www.aquimicasa.net\\\/\"],\"url\":\"https:\\\/\\\/www.aquimicasa.net\\\/blog\\\/author\\\/eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n","description":"Se pretende lograr precios asequibles mediante\u00a0un sistema de seguimiento, informaci\u00f3n y evaluaci\u00f3n de los precios de los alimentos b\u00e1sicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/","og_locale":"es_ES","og_type":"article","og_title":"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n","og_description":"Se pretende lograr precios asequibles mediante\u00a0un sistema de seguimiento, informaci\u00f3n y evaluaci\u00f3n de los precios de los alimentos b\u00e1sicos","og_url":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/","og_site_name":"Blog de aquimicasa.net","article_publisher":"https:\/\/www.facebook.com\/aquimicasa.net","article_published_time":"2023-10-28T18:19:09+00:00","og_image":[{"width":400,"height":304,"url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","type":"image\/jpeg"}],"author":"Eduardo Lizarraga","twitter_misc":{"Escrito por":"Eduardo Lizarraga","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#article","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/"},"author":{"name":"Eduardo Lizarraga","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14"},"headline":"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n","datePublished":"2023-10-28T18:19:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/"},"wordCount":1134,"commentCount":0,"publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","keywords":["inflaci\u00f3n","newsletter 433","noticia de portada"],"articleSection":["Asociaciones de Consumidores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/","url":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/","name":"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n","isPartOf":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#primaryimage"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","datePublished":"2023-10-28T18:19:09+00:00","description":"Se pretende lograr precios asequibles mediante\u00a0un sistema de seguimiento, informaci\u00f3n y evaluaci\u00f3n de los precios de los alimentos b\u00e1sicos","breadcrumb":{"@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#primaryimage","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","width":400,"height":304,"caption":"Las subidas de la alimentaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aquimicasa.net\/blog\/consumo\/asociacion-de-consumidores\/humo-para-ocultar-los-beneficios-empresariales-en-la-alimentacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aquimicasa.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Humo para ocultar los beneficios empresariales en la alimentaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.aquimicasa.net\/blog\/#website","url":"https:\/\/www.aquimicasa.net\/blog\/","name":"Blog de aquimicasa.net","description":"Noticias del Mundo Inmobiliario","publisher":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aquimicasa.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aquimicasa.net\/blog\/#organization","name":"Blog de aquimicasa.net","url":"https:\/\/www.aquimicasa.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","contentUrl":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/Logo-aquimicasa-1-e1528048213782.png","width":225,"height":225,"caption":"Blog de aquimicasa.net"},"image":{"@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aquimicasa.net","https:\/\/www.instagram.com\/","https:\/\/x.com\/EduLizarragaD","https:\/\/www.linkedin.com\/feed\/"]},{"@type":"Person","@id":"https:\/\/www.aquimicasa.net\/blog\/#\/schema\/person\/2cdfa2605534583395c8d7ce1d6cac14","name":"Eduardo Lizarraga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdabe1eeeed97b65a9cb7de2edd624b07995f7e13abc5fead15961f745f908cc?s=96&d=mm&r=g","caption":"Eduardo Lizarraga"},"description":"Periodista Econ\u00f3mico. Ha trabajado en diversos campos de la informaci\u00f3n. Corresponsal en conflictos, analista pol\u00edtico en Congreso y Senado, periodista del medio ambiente, editor, director editorial, director de comunicaci\u00f3n.... En estos momentos se ha especializado en el sector inmobiliario. Pero tambi\u00e9n es navegante y viajero, preocupado por la pobreza, el medio ambiente y por las actuaciones descontroladas del neoliberalismo empresarial y pol\u00edtico en todo el mundo. Los desahucios, la pobreza infantil y la falta de acceso a los suministros b\u00e1sicos son algunos de los grandes dramas de nuestra sociedad y que es preciso solucionar para hacerla m\u00e1s justa. CEO en www.aquimicasa.net","sameAs":["https:\/\/www.aquimicasa.net\/"],"url":"https:\/\/www.aquimicasa.net\/blog\/author\/eduardo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.aquimicasa.net\/blog\/wp-content\/uploads\/alimentacion3-e1687039563133.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/45758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/comments?post=45758"}],"version-history":[{"count":3,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/45758\/revisions"}],"predecessor-version":[{"id":45761,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/posts\/45758\/revisions\/45761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media\/44560"}],"wp:attachment":[{"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/media?parent=45758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/categories?post=45758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquimicasa.net\/blog\/wp-json\/wp\/v2\/tags?post=45758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}